{"id":244619,"date":"2023-04-19T18:27:35","date_gmt":"2023-04-19T16:27:35","guid":{"rendered":"https:\/\/avantemedios.com\/?post_type=project&#038;p=244619"},"modified":"2023-04-20T19:15:39","modified_gmt":"2023-04-20T17:15:39","slug":"egm-aragon-1a-ola-2023","status":"publish","type":"project","link":"https:\/\/avantemedios.com\/ca\/informamos\/egm-aragon-1a-ola-2023\/","title":{"rendered":"EGM ARAG\u00d3N 1\u00aa Ola 2023"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.5.1&#8243; background_enable_color=\u00bboff\u00bb background_enable_image=\u00bboff\u00bb background_position=\u00bbtop_center\u00bb custom_padding=\u00bb9vw||0vw||false|false\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.5.1&#8243; custom_margin=\u00bb|||\u00bb custom_padding=\u00bb0px|0px|0px|0px\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb11vw|0px|0px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.5.1&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/avantemedios.com\/wp-content\/uploads\/2023\/04\/1o-EGM-2023-ARAGON-1-scaled.jpg\u00bb alt=\u00bb1\u00baEGM 2023 ARAG\u00d3N AVANTE\u00bb title_text=\u00bb1\u00ba-EGM-2023-ARAGON\u00bb force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.10.7&#8243; custom_padding=\u00bb||44px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0vw||||false|false\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-2px|auto||auto||\u00bb custom_padding=\u00bb2px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMontserrat|700|||||||\u00bb text_text_color=\u00bb#b2292e\u00bb text_font_size=\u00bb24px\u00bb text_line_height=\u00bb2em\u00bb custom_margin=\u00bb4px||7px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<h1>EGM Arag\u00f3n 1\u00aa Ola de 2023<\/h1>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMontserrat||||||||\u00bb text_text_color=\u00bbrgba(0,0,0,0.67)\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<p style=\"text-align: justify;\">Ya est\u00e1 disponible nuestro primer informe del <strong>EGM de <a href=\"https:\/\/avantemedios.com\/\" target=\"_blank\" rel=\"noopener\">AVANTE<\/a> con la 1\u00aa Ola 2023.<\/strong> Como de costumbre, desgranamos el consumo de medios publicitarios a nivel Arag\u00f3n y el comportamiento de las audiencias en<strong> Radio, Internet, Prensa, Exterior y Revistas.\u00a0<\/strong><\/p>\n<div class=\"ewa-rteLine\" style=\"text-align: justify;\"><span><strong>Internet vuelve a liderar en t\u00e9rminos de penetraci\u00f3n <\/strong>(84,6%), por encima de <strong>Exterior<\/strong> (84,0%) y<strong> Televisi\u00f3n<\/strong> (83,7%). La transformaci\u00f3n de los h\u00e1bitos de los consumidores, la consolidaci\u00f3n de modelos laborales h\u00edbridos, el auge del comercio electr\u00f3nico y el consumo de contenido online bajo demanda, ha incrementado su penetraci\u00f3n en los \u00faltimos meses.<\/span><\/div>\n<div class=\"ewa-rteLine\" style=\"text-align: justify;\"><\/div>\n<div class=\"ewa-rteLine\" style=\"text-align: justify;\"><span><strong>Destaca el crecimiento de las RR.SS.<\/strong> que se colocan en 4\u00aa posici\u00f3n con un incremento del 13,82%, adelantando a la radio convencional. <\/span><\/div>\n<div class=\"ewa-rteLine\" style=\"text-align: justify;\"><\/div>\n<div class=\"ewa-rteLine\" style=\"text-align: justify;\"><span>En l\u00edneas generales se registra un aumento generalizado del consumo de la versi\u00f3n online de los medios, destacando sobre todo el incremento de la televisi\u00f3n online (+20,78%).<\/span><span> <\/span><\/div>\n<p>&nbsp;<\/p>\n<p><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\"><\/span><\/p>\n<h3><span style=\"color: #b2292e;\"><strong>\u00bfTE INTERESA EL INFORME EGM COMPLETO?<\/strong><\/span><\/h3>\n<p><strong>\u00a1Rellena el formulario para poder descargarlo!<\/strong><\/p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-244585\"><form id=\"wpforms-form-244585\" class=\"wpforms-validate wpforms-form\" data-formid=\"244585\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/ca\/wp-json\/wp\/v2\/project\/244619\" data-token=\"c54833ee6477708cb3cbc0317703f65f\" data-token-time=\"1778681002\"><noscript class=\"wpforms-error-noscript\">Activeu el JavaScript al navegador per a poder completar el formulari.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-244585-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-244585-field_1\">Nombre <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-244585-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-244585-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-244585-field_7\">Apellidos <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-244585-field_7\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][7]\" required><\/div><div id=\"wpforms-244585-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-244585-field_2\">Correo electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-244585-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-244585-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-244585-field_4\">Empresa <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-244585-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-244585-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-244585-field_5\">Puesto en la empresa <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-244585-field_5\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-244585-field_6-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"6\"><label class=\"wpforms-field-label wpforms-label-hide\">Acuerdo RGPD  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-244585-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-244585-field_6_1\" name=\"wpforms[fields][6][]\" value=\"He le\u00eddo el &lt;a href=&quot;http:\/\/avantemedios.com\/?page_id=3\/&quot; target=&quot;_blank&quot;&gt;Aviso Legal&lt;\/a&gt; y acepto la &lt;a href=&quot;http:\/\/avantemedios.com\/?page_id=3\/&quot; target=&quot;_blank&quot;&gt;Pol\u00edtica de Privacidad&lt;\/a&gt;\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-244585-field_6_1\">He le\u00eddo el <a href=\"http:\/\/avantemedios.com\/?page_id=3\/\" target=\"_blank\">Aviso Legal<\/a> y acepto la <a href=\"http:\/\/avantemedios.com\/?page_id=3\/\" target=\"_blank\">Pol\u00edtica de Privacidad<\/a> <span class=\"wpforms-required-label\">*<\/span><\/label><\/li><\/ul><\/div><div id=\"wpforms-244585-field_8-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"8\"><ul id=\"wpforms-244585-field_8\"><li class=\"choice-1 depth-1 wpforms-selected\"><input type=\"checkbox\" id=\"wpforms-244585-field_8_1\" name=\"wpforms[fields][8][]\" value=\"Quiero recibir las \u00faltimas noticias e informes de Avante\"   checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-244585-field_8_1\">Quiero recibir las \u00faltimas noticias e informes de Avante<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"244585\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project\/244619\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-244585\" class=\"wpforms-submit my-submit-boton1\" data-alt-text=\"Enviando...\" data-submit-text=\"Descargar Informe\" aria-live=\"assertive\" value=\"wpforms-submit\">Descargar Informe<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><!-- [et_pb_line_break_holder] --><script type=\"text\/javascript\"><!-- [et_pb_line_break_holder] -->    var __ss_noform = __ss_noform || [];<!-- [et_pb_line_break_holder] -->    __ss_noform.push(['baseURI', 'https:\/\/app-3QNB3VA6HG.marketingautomation.services\/webforms\/receivePostback\/MzawMDEzNLc0AgA\/']);<!-- [et_pb_line_break_holder] -->    __ss_noform.push(['endpoint', 'da1c79ee-9d14-4059-a790-32789d43d3d7']);<!-- [et_pb_line_break_holder] --><\/script><!-- [et_pb_line_break_holder] --><script type=\"text\/javascript\" src=\"https:\/\/koi-3QNB3VA6HG.marketingautomation.services\/client\/noform.js?ver=1.24\" ><\/script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb0vw||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0vw||||false|false\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb29px\u00bb text_line_height=\u00bb1.2em\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb25px\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<p><strong>Otros informes relacionados<\/strong><\/p>[\/et_pb_text][et_pb_portfolio fullwidth=\u00bboff\u00bb posts_number=\u00bb4&#8243; include_categories=\u00bb37&#8243; show_pagination=\u00bboff\u00bb zoom_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(176,39,45,0.7)\u00bb _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|700|||||||\u00bb caption_font=\u00bb|600|||||||\u00bb caption_text_color=\u00bb#000000&#8243; title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb21px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_portfolio][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Informe EGM 1\u00aa Ola de 2023. Datos y an\u00e1lisis de consumo de medios en Arag\u00f3n.<\/p>","protected":false},"author":5,"featured_media":244673,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"project_category":[37,15],"project_tag":[88,86,87],"class_list":["post-244619","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-aragon","project_category-egm","project_tag-medios-publicitarios","project_tag-informes","project_tag-egm"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project\/244619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/comments?post=244619"}],"version-history":[{"count":8,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project\/244619\/revisions"}],"predecessor-version":[{"id":244848,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project\/244619\/revisions\/244848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/media\/244673"}],"wp:attachment":[{"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/media?parent=244619"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project_category?post=244619"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project_tag?post=244619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}