{"id":249243,"date":"2025-07-03T09:30:25","date_gmt":"2025-07-03T07:30:25","guid":{"rendered":"https:\/\/avantemedios.com\/?post_type=project&#038;p=249243"},"modified":"2025-07-04T09:10:37","modified_gmt":"2025-07-04T07:10:37","slug":"egm-aragon-2a-ola-2025","status":"publish","type":"project","link":"https:\/\/avantemedios.com\/ca\/informamos\/egm-aragon-2a-ola-2025\/","title":{"rendered":"EGM ARAG\u00d3N 2\u00aa Ola 2025"},"content":{"rendered":"[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; background_enable_color=\u00bboff\u00bb background_enable_image=\u00bboff\u00bb background_position=\u00bbtop_center\u00bb custom_padding=\u00bb9vw||0vw||false|false\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|||\u00bb custom_padding=\u00bb0px|0px|0px|0px\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb11vw|0px|0px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/avantemedios.com\/wp-content\/uploads\/2025\/07\/2o-EGM-2025_ARAGON_AVANTE.jpg\u00bb alt=\u00bb2\u00ba EGM 2025_ARAG\u00d3N_AVANTE\u00bb title_text=\u00bb2\u00ba EGM 2025_ARAG\u00d3N_AVANTE\u00bb force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.24.0&#8243; custom_padding=\u00bb||44px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0vw||||false|false\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-2px|auto||auto||\u00bb custom_padding=\u00bb2px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMontserrat|700|||||||\u00bb text_text_color=\u00bb#b2292e\u00bb text_font_size=\u00bb24px\u00bb text_line_height=\u00bb2em\u00bb custom_margin=\u00bb4px||7px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]\n<h1>EGM Arag\u00f3n 2\u00aa Ola de 2025<\/h1>\n[\/et_pb_text][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||9px|||\u00bb global_colors_info=\u00bb{}\u00bb]\n<div align=\"justify\">\n<p align=\"justify\" style=\"text-align: justify;\"><span style=\"color: #b2292e;\"><em>Julio, 2025<\/em><\/span><\/p>\n<\/div>\n[\/et_pb_text][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMontserrat||||||||\u00bb text_text_color=\u00bbrgba(0,0,0,0.67)\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]\n<div class=\"ewa-rteLine\" style=\"text-align: justify;\">\n<p>Desde AVANTE, agencia de medios con experiencia sectorial y servicios de publicidad integral, ofrecemos planificaci\u00f3n de medios y compra de espacio publicitario adaptada a los entornos regionales. Dise\u00f1amos campa\u00f1as basadas en an\u00e1lisis de audiencias y resultados medibles.<\/p>\n<p>En Arag\u00f3n, <strong>Internet<\/strong> lidera como canal m\u00e1s consumido, seguido muy de cerca por el medio <strong>Exterior<\/strong>, ambos por encima del 87% de cobertura. La <strong>Televisi\u00f3n<\/strong> convencional baja ligeramente (80,8%), mientras que la televisi\u00f3n online y las plataformas de v\u00eddeo bajo demanda siguen creciendo.<\/p>\n<p><strong>Redes Sociales<\/strong> como Instagram, TikTok y YouTube consolidan su presencia, y la mensajer\u00eda instant\u00e1nea sigue siendo uno de los usos m\u00e1s frecuentes. La <strong>Radio<\/strong> supera el 50% de penetraci\u00f3n, con Cadena SER como l\u00edder y un crecimiento destacado de COPE. La prensa tambi\u00e9n gana relevancia, liderada por Heraldo de Arag\u00f3n, y el cine se mantiene como medio minoritario.<\/p>\n<\/div>\n<h3 class=\"ewa-rteLine\" style=\"text-align: justify;\"><span style=\"color: #b2292e;\"><strong><\/strong><\/span><\/h3>\n<h3 class=\"ewa-rteLine\" style=\"text-align: justify;\"><span style=\"color: #b2292e;\"><strong><\/strong><\/span><\/h3>\n<h3 class=\"ewa-rteLine\" style=\"text-align: justify;\"><span style=\"color: #b2292e;\"><strong><\/strong><\/span><\/h3>\n<h3 class=\"ewa-rteLine\" style=\"text-align: justify;\"><span style=\"color: #b2292e;\"><strong>\u00bfTE INTERESA EL INFORME EGM COMPLETO?<\/strong><\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>\u00a1Rellena el formulario para poder descargarlo!<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-249200\"><form id=\"wpforms-form-249200\" class=\"wpforms-validate wpforms-form\" data-formid=\"249200\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/ca\/wp-json\/wp\/v2\/project\/249243\" data-token=\"f4de3880cbb5965d38bd38f5c778fc2b\" data-token-time=\"1778675658\"><noscript class=\"wpforms-error-noscript\">Activeu el JavaScript al navegador per a poder completar el formulari.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-249200-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-249200-field_1\">Nombre completo <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-249200-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" placeholder=\"Nombre\" required><label for=\"wpforms-249200-field_1\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-249200-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" placeholder=\"Apellidos\" required><label for=\"wpforms-249200-field_1-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Cognoms<\/label><\/div><\/div><\/div><div id=\"wpforms-249200-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-249200-field_2\">Correo electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-249200-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-249200-field_10-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-249200-field_10\">Provincia <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-249200-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" required=\"required\"><option value=\"\u00c1lava\"  selected='selected' class=\"choice-4 depth-1\"  >\u00c1lava<\/option><option value=\"Albacete\"  class=\"choice-5 depth-1\"  >Albacete<\/option><option value=\"Alicante\"  class=\"choice-6 depth-1\"  >Alicante<\/option><option value=\"Almer\u00eda\"  class=\"choice-7 depth-1\"  >Almer\u00eda<\/option><option value=\"Asturias\"  class=\"choice-8 depth-1\"  >Asturias<\/option><option value=\"\u00c1vila\"  class=\"choice-9 depth-1\"  >\u00c1vila<\/option><option value=\"Badajoz\"  class=\"choice-10 depth-1\"  >Badajoz<\/option><option value=\"Barcelona\"  class=\"choice-11 depth-1\"  >Barcelona<\/option><option value=\"Burgos\"  class=\"choice-12 depth-1\"  >Burgos<\/option><option value=\"C\u00e1ceres\"  class=\"choice-13 depth-1\"  >C\u00e1ceres<\/option><option value=\"C\u00e1diz\"  class=\"choice-14 depth-1\"  >C\u00e1diz<\/option><option value=\"Cantabria\"  class=\"choice-15 depth-1\"  >Cantabria<\/option><option value=\"Castell\u00f3n\"  class=\"choice-16 depth-1\"  >Castell\u00f3n<\/option><option value=\"Ciudad Real\"  class=\"choice-17 depth-1\"  >Ciudad Real<\/option><option value=\"C\u00f3rdoba\"  class=\"choice-18 depth-1\"  >C\u00f3rdoba<\/option><option value=\"La Coru\u00f1a\"  class=\"choice-19 depth-1\"  >La Coru\u00f1a<\/option><option value=\"Cuenca\"  class=\"choice-20 depth-1\"  >Cuenca<\/option><option value=\"Gerona\"  class=\"choice-21 depth-1\"  >Gerona<\/option><option value=\"Granada\"  class=\"choice-22 depth-1\"  >Granada<\/option><option value=\"Guadalajara\"  class=\"choice-23 depth-1\"  >Guadalajara<\/option><option value=\"Guip\u00fazcoa\"  class=\"choice-24 depth-1\"  >Guip\u00fazcoa<\/option><option value=\"Huelva\"  class=\"choice-25 depth-1\"  >Huelva<\/option><option value=\"Huesca\"  class=\"choice-26 depth-1\"  >Huesca<\/option><option value=\"Islas Baleares\"  class=\"choice-27 depth-1\"  >Islas Baleares<\/option><option value=\"Ja\u00e9n\"  class=\"choice-28 depth-1\"  >Ja\u00e9n<\/option><option value=\"Le\u00f3n\"  class=\"choice-29 depth-1\"  >Le\u00f3n<\/option><option value=\"L\u00e9rida\"  class=\"choice-30 depth-1\"  >L\u00e9rida<\/option><option value=\"Lugo\"  class=\"choice-31 depth-1\"  >Lugo<\/option><option value=\"Madrid\"  class=\"choice-32 depth-1\"  >Madrid<\/option><option value=\"M\u00e1laga\"  class=\"choice-33 depth-1\"  >M\u00e1laga<\/option><option value=\"Murcia\"  class=\"choice-34 depth-1\"  >Murcia<\/option><option value=\"Navarra\"  class=\"choice-35 depth-1\"  >Navarra<\/option><option value=\"Orense\"  class=\"choice-36 depth-1\"  >Orense<\/option><option value=\"Palencia\"  class=\"choice-37 depth-1\"  >Palencia<\/option><option value=\"Pontevedra\"  class=\"choice-39 depth-1\"  >Pontevedra<\/option><option value=\"La Rioja\"  class=\"choice-40 depth-1\"  >La Rioja<\/option><option value=\"Salamanca\"  class=\"choice-41 depth-1\"  >Salamanca<\/option><option value=\"Segovia\"  class=\"choice-42 depth-1\"  >Segovia<\/option><option value=\"Sevilla\"  class=\"choice-43 depth-1\"  >Sevilla<\/option><option value=\"Soria\"  class=\"choice-44 depth-1\"  >Soria<\/option><option value=\"Tarragona\"  class=\"choice-45 depth-1\"  >Tarragona<\/option><option value=\"Islas Canarias\"  class=\"choice-46 depth-1\"  >Islas Canarias<\/option><option value=\"Teruel\"  class=\"choice-47 depth-1\"  >Teruel<\/option><option value=\"Toledo\"  class=\"choice-48 depth-1\"  >Toledo<\/option><option value=\"Valencia\"  class=\"choice-49 depth-1\"  >Valencia<\/option><option value=\"Valladolid\"  class=\"choice-50 depth-1\"  >Valladolid<\/option><option value=\"Vizcaya\"  class=\"choice-51 depth-1\"  >Vizcaya<\/option><option value=\"Zamora\"  class=\"choice-52 depth-1\"  >Zamora<\/option><option value=\"Zaragoza\"  class=\"choice-53 depth-1\"  >Zaragoza<\/option><\/select><\/div><div id=\"wpforms-249200-field_9-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-249200-field_9\">Pa\u00eds <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-249200-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" required=\"required\"><option value=\"Afganist\u00e1n\"  class=\"choice-4 depth-1\"  >Afganist\u00e1n<\/option><option value=\"Albania\"  class=\"choice-5 depth-1\"  >Albania<\/option><option value=\"Alemania\"  class=\"choice-6 depth-1\"  >Alemania<\/option><option value=\"Andorra\"  class=\"choice-7 depth-1\"  >Andorra<\/option><option value=\"Angola\"  class=\"choice-8 depth-1\"  >Angola<\/option><option value=\"Antigua y Barbuda\"  class=\"choice-9 depth-1\"  >Antigua y Barbuda<\/option><option value=\"Arabia Saudita\"  class=\"choice-10 depth-1\"  >Arabia Saudita<\/option><option value=\"Argelia\"  class=\"choice-11 depth-1\"  >Argelia<\/option><option value=\"Argentina\"  class=\"choice-12 depth-1\"  >Argentina<\/option><option value=\"Armenia\"  class=\"choice-13 depth-1\"  >Armenia<\/option><option value=\"Australia\"  class=\"choice-14 depth-1\"  >Australia<\/option><option value=\"Austria\"  class=\"choice-15 depth-1\"  >Austria<\/option><option value=\"Azerbaiy\u00e1n\"  class=\"choice-16 depth-1\"  >Azerbaiy\u00e1n<\/option><option value=\"Bahamas\"  class=\"choice-17 depth-1\"  >Bahamas<\/option><option value=\"Banglad\u00e9s\"  class=\"choice-18 depth-1\"  >Banglad\u00e9s<\/option><option value=\"Barbados\"  class=\"choice-19 depth-1\"  >Barbados<\/option><option value=\"Bar\u00e9in\"  class=\"choice-20 depth-1\"  >Bar\u00e9in<\/option><option value=\"B\u00e9lgica\"  class=\"choice-21 depth-1\"  >B\u00e9lgica<\/option><option value=\"Belice\"  class=\"choice-22 depth-1\"  >Belice<\/option><option value=\"Ben\u00edn\"  class=\"choice-23 depth-1\"  >Ben\u00edn<\/option><option value=\"Bielorrusia\"  class=\"choice-24 depth-1\"  >Bielorrusia<\/option><option value=\"Birmania (Myanmar)\"  class=\"choice-25 depth-1\"  >Birmania (Myanmar)<\/option><option value=\"Bolivia\"  class=\"choice-26 depth-1\"  >Bolivia<\/option><option value=\"Bosnia y Herzegovina\"  class=\"choice-27 depth-1\"  >Bosnia y Herzegovina<\/option><option value=\"Botsuana\"  class=\"choice-28 depth-1\"  >Botsuana<\/option><option value=\"Brasil\"  class=\"choice-29 depth-1\"  >Brasil<\/option><option value=\"Brun\u00e9i\"  class=\"choice-30 depth-1\"  >Brun\u00e9i<\/option><option value=\"Bulgaria\"  class=\"choice-31 depth-1\"  >Bulgaria<\/option><option value=\"Burkina Faso\"  class=\"choice-32 depth-1\"  >Burkina Faso<\/option><option value=\"Burundi\"  class=\"choice-33 depth-1\"  >Burundi<\/option><option value=\"But\u00e1n\"  class=\"choice-34 depth-1\"  >But\u00e1n<\/option><option value=\"Cabo Verde\"  class=\"choice-35 depth-1\"  >Cabo Verde<\/option><option value=\"Camboya\"  class=\"choice-36 depth-1\"  >Camboya<\/option><option value=\"Camer\u00fan\"  class=\"choice-37 depth-1\"  >Camer\u00fan<\/option><option value=\"Canad\u00e1\"  class=\"choice-38 depth-1\"  >Canad\u00e1<\/option><option value=\"Catar\"  class=\"choice-39 depth-1\"  >Catar<\/option><option value=\"Chad\"  class=\"choice-40 depth-1\"  >Chad<\/option><option value=\"Chile\"  class=\"choice-41 depth-1\"  >Chile<\/option><option value=\"China\"  class=\"choice-42 depth-1\"  >China<\/option><option value=\"Chipre\"  class=\"choice-43 depth-1\"  >Chipre<\/option><option value=\"Ciudad del Vaticano\"  class=\"choice-44 depth-1\"  >Ciudad del Vaticano<\/option><option value=\"Colombia\"  class=\"choice-45 depth-1\"  >Colombia<\/option><option value=\"Comoras\"  class=\"choice-46 depth-1\"  >Comoras<\/option><option value=\"Corea del Norte\"  class=\"choice-47 depth-1\"  >Corea del Norte<\/option><option value=\"Corea del Sur\"  class=\"choice-48 depth-1\"  >Corea del Sur<\/option><option value=\"Costa de Marfil\"  class=\"choice-49 depth-1\"  >Costa de Marfil<\/option><option value=\"Costa Rica\"  class=\"choice-50 depth-1\"  >Costa Rica<\/option><option value=\"Croacia\"  class=\"choice-51 depth-1\"  >Croacia<\/option><option value=\"Cuba\"  class=\"choice-52 depth-1\"  >Cuba<\/option><option value=\"Dinamarca\"  class=\"choice-53 depth-1\"  >Dinamarca<\/option><option value=\"Dominica\"  class=\"choice-54 depth-1\"  >Dominica<\/option><option value=\"Ecuador\"  class=\"choice-55 depth-1\"  >Ecuador<\/option><option value=\"Egipto\"  class=\"choice-56 depth-1\"  >Egipto<\/option><option value=\"El Salvador\"  class=\"choice-57 depth-1\"  >El Salvador<\/option><option value=\"Emiratos \u00c1rabes Unidos\"  class=\"choice-58 depth-1\"  >Emiratos \u00c1rabes Unidos<\/option><option value=\"Eritrea\"  class=\"choice-59 depth-1\"  >Eritrea<\/option><option value=\"Eslovaquia\"  class=\"choice-60 depth-1\"  >Eslovaquia<\/option><option value=\"Eslovenia\"  class=\"choice-61 depth-1\"  >Eslovenia<\/option><option value=\"Espa\u00f1a\"  selected='selected' class=\"choice-62 depth-1\"  >Espa\u00f1a<\/option><option value=\"Estados Unidos\"  class=\"choice-63 depth-1\"  >Estados Unidos<\/option><option value=\"Estonia\"  class=\"choice-64 depth-1\"  >Estonia<\/option><option value=\"Etiop\u00eda\"  class=\"choice-65 depth-1\"  >Etiop\u00eda<\/option><option value=\"Filipinas\"  class=\"choice-66 depth-1\"  >Filipinas<\/option><option value=\"Finlandia\"  class=\"choice-67 depth-1\"  >Finlandia<\/option><option value=\"Fiyi\"  class=\"choice-68 depth-1\"  >Fiyi<\/option><option value=\"Francia\"  class=\"choice-69 depth-1\"  >Francia<\/option><option value=\"Gab\u00f3n\"  class=\"choice-70 depth-1\"  >Gab\u00f3n<\/option><option value=\"Gambia\"  class=\"choice-71 depth-1\"  >Gambia<\/option><option value=\"Georgia\"  class=\"choice-72 depth-1\"  >Georgia<\/option><option value=\"Ghana\"  class=\"choice-73 depth-1\"  >Ghana<\/option><option value=\"Granada\"  class=\"choice-74 depth-1\"  >Granada<\/option><option value=\"Grecia\"  class=\"choice-75 depth-1\"  >Grecia<\/option><option value=\"Guatemala\"  class=\"choice-76 depth-1\"  >Guatemala<\/option><option value=\"Guinea\"  class=\"choice-77 depth-1\"  >Guinea<\/option><option value=\"Guinea Ecuatorial\"  class=\"choice-78 depth-1\"  >Guinea Ecuatorial<\/option><option value=\"Guinea-Bis\u00e1u\"  class=\"choice-79 depth-1\"  >Guinea-Bis\u00e1u<\/option><option value=\"Guyana\"  class=\"choice-80 depth-1\"  >Guyana<\/option><option value=\"Hait\u00ed\"  class=\"choice-81 depth-1\"  >Hait\u00ed<\/option><option value=\"Honduras\"  class=\"choice-82 depth-1\"  >Honduras<\/option><option value=\"Hungr\u00eda\"  class=\"choice-83 depth-1\"  >Hungr\u00eda<\/option><option value=\"India\"  class=\"choice-84 depth-1\"  >India<\/option><option value=\"Indonesia\"  class=\"choice-85 depth-1\"  >Indonesia<\/option><option value=\"Irak\"  class=\"choice-86 depth-1\"  >Irak<\/option><option value=\"Ir\u00e1n\"  class=\"choice-87 depth-1\"  >Ir\u00e1n<\/option><option value=\"Irlanda\"  class=\"choice-88 depth-1\"  >Irlanda<\/option><option value=\"Islandia\"  class=\"choice-89 depth-1\"  >Islandia<\/option><option value=\"Islas Marshall\"  class=\"choice-90 depth-1\"  >Islas Marshall<\/option><option value=\"Islas Salom\u00f3n\"  class=\"choice-91 depth-1\"  >Islas Salom\u00f3n<\/option><option value=\"Israel\"  class=\"choice-92 depth-1\"  >Israel<\/option><option value=\"Italia\"  class=\"choice-93 depth-1\"  >Italia<\/option><option value=\"Jamaica\"  class=\"choice-94 depth-1\"  >Jamaica<\/option><option value=\"Jap\u00f3n\"  class=\"choice-95 depth-1\"  >Jap\u00f3n<\/option><option value=\"Jordania\"  class=\"choice-96 depth-1\"  >Jordania<\/option><option value=\"Kazajist\u00e1n\"  class=\"choice-97 depth-1\"  >Kazajist\u00e1n<\/option><option value=\"Kenia\"  class=\"choice-98 depth-1\"  >Kenia<\/option><option value=\"Kirguist\u00e1n\"  class=\"choice-99 depth-1\"  >Kirguist\u00e1n<\/option><option value=\"Kiribati\"  class=\"choice-100 depth-1\"  >Kiribati<\/option><option value=\"Kuwait\"  class=\"choice-101 depth-1\"  >Kuwait<\/option><option value=\"Laos\"  class=\"choice-102 depth-1\"  >Laos<\/option><option value=\"Lesoto\"  class=\"choice-103 depth-1\"  >Lesoto<\/option><\/select><\/div><div id=\"wpforms-249200-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-249200-field_4\">Empresa <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-249200-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-249200-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-249200-field_5\">Puesto en la empresa <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-249200-field_5\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-249200-field_6-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"6\"><label class=\"wpforms-field-label wpforms-label-hide\">Acuerdo RGPD  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-249200-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-249200-field_6_1\" name=\"wpforms[fields][6][]\" value=\"He le\u00eddo el &lt;a href=&quot;http:\/\/avantemedios.com\/?page_id=3\/&quot; target=&quot;_blank&quot;&gt;Aviso Legal&lt;\/a&gt; y acepto la &lt;a href=&quot;http:\/\/avantemedios.com\/?page_id=3\/&quot; target=&quot;_blank&quot;&gt;Pol\u00edtica de Privacidad&lt;\/a&gt;\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-249200-field_6_1\">He le\u00eddo el <a href=\"http:\/\/avantemedios.com\/?page_id=3\/\" target=\"_blank\">Aviso Legal<\/a> y acepto la <a href=\"http:\/\/avantemedios.com\/?page_id=3\/\" target=\"_blank\">Pol\u00edtica de Privacidad<\/a> <span class=\"wpforms-required-label\">*<\/span><\/label><\/li><\/ul><\/div><div id=\"wpforms-249200-field_8-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"8\"><ul id=\"wpforms-249200-field_8\"><li class=\"choice-1 depth-1 wpforms-selected\"><input type=\"checkbox\" id=\"wpforms-249200-field_8_1\" name=\"wpforms[fields][8][]\" value=\"Quiero recibir las \u00faltimas noticias e informes de AVANTE\"   checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-249200-field_8_1\">Quiero recibir las \u00faltimas noticias e informes de AVANTE<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"249200\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project\/249243\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-249200\" class=\"wpforms-submit my-submit-boton1\" data-alt-text=\"Enviando...\" data-submit-text=\"Descargar Informe\" aria-live=\"assertive\" value=\"wpforms-submit\">Descargar Informe<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><!-- [et_pb_line_break_holder] --><script type=\"text\/javascript\"><!-- [et_pb_line_break_holder] -->    var __ss_noform = __ss_noform || [];<!-- [et_pb_line_break_holder] -->    __ss_noform.push(['baseURI', 'https:\/\/app-3QNB3VA6HG.marketingautomation.services\/webforms\/receivePostback\/MzawMDEzNLc0AgA\/']);<!-- [et_pb_line_break_holder] -->    __ss_noform.push(['endpoint', '2132d368-0944-4f41-913f-e88fac585891']);<!-- [et_pb_line_break_holder] --><\/script><!-- [et_pb_line_break_holder] --><script type=\"text\/javascript\" src=\"https:\/\/koi-3QNB3VA6HG.marketingautomation.services\/client\/noform.js?ver=1.24\" ><\/script><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb0vw||||false|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0vw||||false|false\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb29px\u00bb text_line_height=\u00bb1.2em\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb25px\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]\n<p><strong>Otros informes relacionados<\/strong><\/p>\n[\/et_pb_text][et_pb_portfolio fullwidth=\u00bboff\u00bb posts_number=\u00bb4&#8243; include_categories=\u00bb37&#8243; show_pagination=\u00bboff\u00bb zoom_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(176,39,45,0.7)\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|700|||||||\u00bb caption_font=\u00bb|600|||||||\u00bb caption_text_color=\u00bb#000000&#8243; title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb21px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_portfolio][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>EGM Arag\u00f3n 2\u00aa Ola de 2025. Disponible el tercer informe de datos y an\u00e1lisis de consumo de medios en la comunidad aut\u00f3noma de Arag\u00f3n.<\/p>","protected":false},"author":5,"featured_media":249264,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"project_category":[37,15],"project_tag":[88,86,87],"class_list":["post-249243","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-aragon","project_category-egm","project_tag-medios-publicitarios","project_tag-informes","project_tag-egm"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project\/249243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/comments?post=249243"}],"version-history":[{"count":5,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project\/249243\/revisions"}],"predecessor-version":[{"id":249381,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project\/249243\/revisions\/249381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/media\/249264"}],"wp:attachment":[{"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/media?parent=249243"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project_category?post=249243"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/avantemedios.com\/ca\/wp-json\/wp\/v2\/project_tag?post=249243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}