{"id":242891,"date":"2022-07-05T08:45:00","date_gmt":"2022-07-05T06:45:00","guid":{"rendered":"https:\/\/avantemedios.com\/?post_type=project&#038;p=242891"},"modified":"2022-07-06T10:07:40","modified_gmt":"2022-07-06T08:07:40","slug":"egm-2o-acumulado-movil-2022-aragon","status":"publish","type":"project","link":"https:\/\/avantemedios.com\/eu\/informamos\/egm-2o-acumulado-movil-2022-aragon\/","title":{"rendered":"EGM 2\u00ba Acumulado M\u00f3vil 2022 ARAG\u00d3N"},"content":{"rendered":"[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.5.1&#8243; background_enable_color=\u00bboff\u00bb background_enable_image=\u00bboff\u00bb background_position=\u00bbtop_center\u00bb custom_padding=\u00bb9vw||0vw||false|false\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.5.1&#8243; custom_margin=\u00bb|||\u00bb custom_padding=\u00bb0px|0px|0px|0px\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb11vw|0px|0px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.5.1&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/avantemedios.com\/wp-content\/uploads\/2022\/07\/Aragon-2oEGM-2022-Avante.jpg\u00bb alt=\u00bbAragon-2oEGM-2022-Avante\u00bb title_text=\u00bbArag\u00f3n-2\u00baEGM 2022-Avante\u00bb force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.10.7&#8243; custom_padding=\u00bb||44px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0vw||||false|false\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-2px|auto||auto||\u00bb custom_padding=\u00bb2px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMontserrat|700|||||||\u00bb text_text_color=\u00bb#b2292e\u00bb text_font_size=\u00bb24px\u00bb text_line_height=\u00bb2em\u00bb custom_margin=\u00bb4px||7px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]\n<h1>2\u00ba EGM ARAG\u00d3N 2022<\/h1>\n[\/et_pb_text][et_pb_text _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMontserrat||||||||\u00bb text_text_color=\u00bbrgba(0,0,0,0.67)\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Ya est\u00e1 disponible el nuevo <strong>informe de EGM de Avante Evolumedia con el 2\u00ba Acumulado M\u00f3vil en Arag\u00f3n<\/strong>, en el que se muestra el an\u00e1lisis de los medios publicitarios en este 2\u00ba trimestre de 2022.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">En este 2\u00ba Acumulado encontramos un <strong>crecimiento generalizado de todos los medios salvo Televisi\u00f3n que cae<\/strong> (-1,05%), a pesar de ocupar la primera posici\u00f3n, y Diarios (-0,64%).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\"><strong>Exterior<\/strong> es el medio que sufre una subida menos acusada (+0,42%) junto con la <strong>Radio<\/strong> (+0,59%), mientras que los <strong>SSDD (+8,67%), Revistas, (+2,25%%) e Internet (+1,58%) son los que m\u00e1s crecen.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Entre las versiones online de los medios de comunicaci\u00f3n, los Diarios online contin\u00faan siendo los m\u00e1s consumidos.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\"><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\"><\/span><\/p>\n<p><span style=\"color: #008080;\"><strong>\u00bfTE INTERESA EL INFORME COMPLETO?<\/strong><\/span><\/p>\n<p><strong>\u00a1Rellena el formulario para poder descargarlo!<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-242846\"><form id=\"wpforms-form-242846\" class=\"wpforms-validate wpforms-form\" data-formid=\"242846\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/eu\/wp-json\/wp\/v2\/project\/242891\" data-token=\"6cfe4b9b96303ab734a572a94b523acc\" data-token-time=\"1778682647\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-242846-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-242846-field_1\">Nombre <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-242846-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-242846-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-242846-field_7\">Apellidos <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-242846-field_7\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][7]\" required><\/div><div id=\"wpforms-242846-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-242846-field_2\">Correo electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-242846-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-242846-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-242846-field_4\">Empresa <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-242846-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-242846-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-242846-field_5\">Puesto en la empresa <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-242846-field_5\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-242846-field_6-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"6\"><label class=\"wpforms-field-label wpforms-label-hide\">Acuerdo RGPD  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-242846-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-242846-field_6_1\" name=\"wpforms[fields][6][]\" value=\"He le\u00eddo el &lt;a href=&quot;http:\/\/avantemedios.com\/?page_id=3\/&quot; target=&quot;_blank&quot;&gt;Aviso Legal&lt;\/a&gt; y acepto la &lt;a href=&quot;http:\/\/avantemedios.com\/?page_id=3\/&quot; target=&quot;_blank&quot;&gt;Pol\u00edtica de Privacidad&lt;\/a&gt;\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-242846-field_6_1\">He le\u00eddo el <a href=\"http:\/\/avantemedios.com\/?page_id=3\/\" target=\"_blank\">Aviso Legal<\/a> y acepto la <a href=\"http:\/\/avantemedios.com\/?page_id=3\/\" target=\"_blank\">Pol\u00edtica de Privacidad<\/a> <span class=\"wpforms-required-label\">*<\/span><\/label><\/li><\/ul><\/div><div id=\"wpforms-242846-field_8-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"8\"><ul id=\"wpforms-242846-field_8\"><li class=\"choice-1 depth-1 wpforms-selected\"><input type=\"checkbox\" id=\"wpforms-242846-field_8_1\" name=\"wpforms[fields][8][]\" value=\"Quiero recibir las \u00faltimas noticias e informes de Avante\"   checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-242846-field_8_1\">Quiero recibir las \u00faltimas noticias e informes de Avante<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"242846\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/project\/242891\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-242846\" class=\"wpforms-submit my-submit-boton1\" data-alt-text=\"Enviando...\" data-submit-text=\"Descargar Informe\" aria-live=\"assertive\" value=\"wpforms-submit\">Descargar Informe<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><!-- [et_pb_line_break_holder] --><script type=\"text\/javascript\"><!-- [et_pb_line_break_holder] -->    var __ss_noform = __ss_noform || [];<!-- [et_pb_line_break_holder] -->    __ss_noform.push(['baseURI', 'https:\/\/app-3QNB3VA6HG.marketingautomation.services\/webforms\/receivePostback\/MzawMDEzNLc0AgA\/']);<!-- [et_pb_line_break_holder] -->    __ss_noform.push(['endpoint', '7568b5e4-6660-438c-9b56-7cb53fb95d14']);<!-- [et_pb_line_break_holder] --><\/script><!-- [et_pb_line_break_holder] --><script type=\"text\/javascript\" src=\"https:\/\/koi-3QNB3VA6HG.marketingautomation.services\/client\/noform.js?ver=1.24\" ><\/script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb0vw||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0vw||||false|false\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.5.1&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb29px\u00bb text_line_height=\u00bb1.2em\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb25px\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]\n<p><strong>Otros informes relacionados<\/strong><\/p>\n[\/et_pb_text][et_pb_portfolio fullwidth=\u00bboff\u00bb posts_number=\u00bb4&#8243; include_categories=\u00bb37&#8243; show_pagination=\u00bboff\u00bb zoom_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(176,39,45,0.7)\u00bb _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|700|||||||\u00bb caption_font=\u00bb|600|||||||\u00bb caption_text_color=\u00bb#000000&#8243; title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb21px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_portfolio][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Informe EGM Nacional 2\u00ba Acumulado M\u00f3vil de Marzo a Junio 2022. Datos y an\u00e1lisis de consumo de medios en Arag\u00f3n.<\/p>","protected":false},"author":4,"featured_media":242902,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"project_category":[37,15],"project_tag":[86,87,88],"class_list":["post-242891","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-aragon","project_category-egm","project_tag-informes","project_tag-egm","project_tag-medios-publicitarios"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/project\/242891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/comments?post=242891"}],"version-history":[{"count":7,"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/project\/242891\/revisions"}],"predecessor-version":[{"id":243001,"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/project\/242891\/revisions\/243001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/media\/242902"}],"wp:attachment":[{"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/media?parent=242891"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/project_category?post=242891"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/avantemedios.com\/eu\/wp-json\/wp\/v2\/project_tag?post=242891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}